{"id":1298,"date":"2018-08-14T16:13:18","date_gmt":"2018-08-14T15:13:18","guid":{"rendered":"https:\/\/www.astralsecurite.ca\/blogue\/?p=1298"},"modified":"2025-02-05T16:23:10","modified_gmt":"2025-02-05T15:23:10","slug":"survivre-a-la-canicule-grace-a-la-domotique","status":"publish","type":"post","link":"https:\/\/www.astralsecurite.ca\/blogue\/survivre-a-la-canicule-grace-a-la-domotique\/","title":{"rendered":"Survivre \u00e0 la canicule gr\u00e2ce \u00e0 la domotique"},"content":{"rendered":"<p>Les canicules reviennent chaque \u00e9t\u00e9, plus fortes et plus longues \u00e0 chaque fois. Le mois de juillet que l\u2019on vient de passer a d\u2019ailleurs \u00e9t\u00e9 l\u2019un des plus chauds. Ces canicules \u00e9crasantes ne dispara\u00eetront pas de sit\u00f4t, comme elles sont intimement li\u00e9es aux changements climatiques caus\u00e9s par les \u00e9missions de gaz \u00e0 effet de serre. Que pouvez-vous faire pour vous assurer confort et s\u00e9curit\u00e9 dans votre domicile durant ces \u00e9pisodes de chaleur ?<!--more--><\/p>\n<h2>Contr\u00f4ler la temp\u00e9rature \u00e0 distance<\/h2>\n<p>Gr\u00e2ce \u00e0 la domotique, vous pouvez r\u00e9gler la temp\u00e9rature \u00e0 distance \u00e0 partir de votre t\u00e9l\u00e9phone intelligent gr\u00e2ce au thermostat interactif, pour que votre r\u00e9sidence soit bien rafra\u00eechie \u00e0 votre retour.<\/p>\n<p>L\u2019application synchronis\u00e9e \u00e0 votre t\u00e9l\u00e9phone portable permet au thermostat Lyric d\u2019Honeywell de savoir o\u00f9 vous vous trouvez en tout temps. Il devine m\u00eame \u00e0 quel moment vous comptez revenir \u00e0 la maison et la temp\u00e9rature ambiante de votre r\u00e9sidence sera ajust\u00e9e en cons\u00e9quence.<\/p>\n<p>Vous pourrez donc vous d\u00e9tendre au retour du travail et dormir confortablement.<\/p>\n<h2>L\u2019\u00e9conomie d\u2019\u00e9nergie<\/h2>\n<p>M\u00eame si la climatisation ne demande pas autant de m\u00e9gawatts que le chauffage en hiver, elle utilise tout de m\u00eame beaucoup d&rsquo;\u00e9lectricit\u00e9 et on pourrait voir le total de nos factures monter. <a href=\"https:\/\/www.astralsecurite.ca\/domotique.php\">Le thermostat intelligent Lyric d\u2019Honeywell d\u00e9termine automatiquement s&rsquo;il faut du chauffage ou de la climatisation<\/a>, en tenant compte de la temp\u00e9rature ext\u00e9rieure, de l\u2019humidit\u00e9 et du climat. Vous pouvez aussi \u00e9tablir un horaire de refroidissement si vous le souhaitez.<\/p>\n<p>Comme ce thermostat interactif est int\u00e9gr\u00e9 \u00e0 votre syst\u00e8me de s\u00e9curit\u00e9, vos habitudes, par exemple l\u2019heure de votre d\u00e9part et celle de votre retour, sont enregistr\u00e9es. Ces donn\u00e9es permettent de cr\u00e9er des programmes mieux adapt\u00e9s, par exemple en augmentant la temp\u00e9rature de quelques degr\u00e9s lorsqu\u2019il n\u2019y a personne \u00e0 la maison, ce qui vous aidera \u00e0 optimiser votre consommation d\u2019\u00e9nergie et \u00e0 \u00e9conomiser de l\u2019argent.<\/p>\n<h2>Prot\u00e9ger nos a\u00een\u00e9s de la chaleur<\/h2>\n<p>Les r\u00e9cents \u00e9pisodes de chaleur accablante ont fait de nombreuses victimes, dont une cinquantaine \u00e0 Montr\u00e9al. Parmi eux, plusieurs personnes \u00e2g\u00e9es, qui sont particuli\u00e8rement tr\u00e8s \u00e0 risques face \u00e0 un \u00e9pisode de canicule. Avec un thermostat intelligent install\u00e9 chez vos parents, vous pourriez vous assurer \u00e0 distance que la climatisation est bien adapt\u00e9e \u00e0 leurs besoins.<\/p>\n<p>Le mois d\u2019ao\u00fbt risque d\u2019\u00eatre encore propice \u00e0 l\u2019utilisation du climatiseur. Pourquoi ne pas songer \u00e0 l\u2019installation d\u2019un syst\u00e8me de domotique r\u00e9sidentielle afin de terminer l\u2019\u00e9t\u00e9 en beaut\u00e9 ?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les canicules reviennent chaque \u00e9t\u00e9, plus fortes et plus longues \u00e0 chaque fois. Le mois de juillet que l\u2019on vient de passer a d\u2019ailleurs \u00e9t\u00e9 l\u2019un des plus chauds. Ces canicules \u00e9crasantes ne dispara\u00eetront pas de sit\u00f4t, comme elles sont intimement li\u00e9es aux changements climatiques caus\u00e9s par les \u00e9missions de gaz \u00e0 effet de serre. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1833,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[91],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.10 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Survivre \u00e0 la canicule gr\u00e2ce \u00e0 la domotique - Le blogue d&#039;Astral S\u00e9curit\u00e9<\/title>\n<meta name=\"description\" content=\"D\u00e9couvrez comment la domotique vous aide \u00e0 maintenir une temp\u00e9rature id\u00e9ale pendant les vagues de chaleur. Solutions intelligentes pour votre confort et votre bien-\u00eatre en p\u00e9riode de canicule.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.astralsecurite.ca\/blogue\/survivre-a-la-canicule-grace-a-la-domotique\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Survivre \u00e0 la canicule gr\u00e2ce \u00e0 la domotique - Le blogue d&#039;Astral S\u00e9curit\u00e9\" \/>\n<meta property=\"og:description\" content=\"D\u00e9couvrez comment la domotique vous aide \u00e0 maintenir une temp\u00e9rature id\u00e9ale pendant les vagues de chaleur. Solutions intelligentes pour votre confort et votre bien-\u00eatre en p\u00e9riode de canicule.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.astralsecurite.ca\/blogue\/survivre-a-la-canicule-grace-a-la-domotique\/\" \/>\n<meta property=\"og:site_name\" content=\"Le blogue d&#039;Astral S\u00e9curit\u00e9\" \/>\n<meta property=\"article:published_time\" content=\"2018-08-14T15:13:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-05T15:23:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.astralsecurite.ca\/blogue\/wp-content\/uploads\/2018\/08\/survivre-a-la-canicule-grace-a-la-domotique.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.astralsecurite.ca\/blogue\/survivre-a-la-canicule-grace-a-la-domotique\/\",\"url\":\"https:\/\/www.astralsecurite.ca\/blogue\/survivre-a-la-canicule-grace-a-la-domotique\/\",\"name\":\"Survivre \u00e0 la canicule gr\u00e2ce \u00e0 la domotique - Le blogue d&#039;Astral S\u00e9curit\u00e9\",\"isPartOf\":{\"@id\":\"https:\/\/www.astralsecurite.ca\/blogue\/#website\"},\"datePublished\":\"2018-08-14T15:13:18+00:00\",\"dateModified\":\"2025-02-05T15:23:10+00:00\",\"author\":{\"@id\":\"https:\/\/www.astralsecurite.ca\/blogue\/#\/schema\/person\/07581139837dabeab77172be7d9e7de0\"},\"description\":\"D\u00e9couvrez comment la domotique vous aide \u00e0 maintenir une temp\u00e9rature id\u00e9ale pendant les vagues de chaleur. Solutions intelligentes pour votre confort et votre bien-\u00eatre en p\u00e9riode de canicule.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.astralsecurite.ca\/blogue\/survivre-a-la-canicule-grace-a-la-domotique\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.astralsecurite.ca\/blogue\/survivre-a-la-canicule-grace-a-la-domotique\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.astralsecurite.ca\/blogue\/survivre-a-la-canicule-grace-a-la-domotique\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.astralsecurite.ca\/blogue\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Survivre \u00e0 la canicule gr\u00e2ce \u00e0 la domotique\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.astralsecurite.ca\/blogue\/#website\",\"url\":\"https:\/\/www.astralsecurite.ca\/blogue\/\",\"name\":\"Le blogue d'Astral S\u00e9curit\u00e9\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.astralsecurite.ca\/blogue\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.astralsecurite.ca\/blogue\/#\/schema\/person\/07581139837dabeab77172be7d9e7de0\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.astralsecurite.ca\/blogue\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f09efbcc57bef47e5e43c37ae4f3f265?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f09efbcc57bef47e5e43c37ae4f3f265?s=96&d=mm&r=g\",\"caption\":\"admin\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Survivre \u00e0 la canicule gr\u00e2ce \u00e0 la domotique - Le blogue d&#039;Astral S\u00e9curit\u00e9","description":"D\u00e9couvrez comment la domotique vous aide \u00e0 maintenir une temp\u00e9rature id\u00e9ale pendant les vagues de chaleur. Solutions intelligentes pour votre confort et votre bien-\u00eatre en p\u00e9riode de canicule.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.astralsecurite.ca\/blogue\/survivre-a-la-canicule-grace-a-la-domotique\/","og_locale":"fr_FR","og_type":"article","og_title":"Survivre \u00e0 la canicule gr\u00e2ce \u00e0 la domotique - Le blogue d&#039;Astral S\u00e9curit\u00e9","og_description":"D\u00e9couvrez comment la domotique vous aide \u00e0 maintenir une temp\u00e9rature id\u00e9ale pendant les vagues de chaleur. Solutions intelligentes pour votre confort et votre bien-\u00eatre en p\u00e9riode de canicule.","og_url":"https:\/\/www.astralsecurite.ca\/blogue\/survivre-a-la-canicule-grace-a-la-domotique\/","og_site_name":"Le blogue d&#039;Astral S\u00e9curit\u00e9","article_published_time":"2018-08-14T15:13:18+00:00","article_modified_time":"2025-02-05T15:23:10+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/www.astralsecurite.ca\/blogue\/wp-content\/uploads\/2018\/08\/survivre-a-la-canicule-grace-a-la-domotique.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.astralsecurite.ca\/blogue\/survivre-a-la-canicule-grace-a-la-domotique\/","url":"https:\/\/www.astralsecurite.ca\/blogue\/survivre-a-la-canicule-grace-a-la-domotique\/","name":"Survivre \u00e0 la canicule gr\u00e2ce \u00e0 la domotique - Le blogue d&#039;Astral S\u00e9curit\u00e9","isPartOf":{"@id":"https:\/\/www.astralsecurite.ca\/blogue\/#website"},"datePublished":"2018-08-14T15:13:18+00:00","dateModified":"2025-02-05T15:23:10+00:00","author":{"@id":"https:\/\/www.astralsecurite.ca\/blogue\/#\/schema\/person\/07581139837dabeab77172be7d9e7de0"},"description":"D\u00e9couvrez comment la domotique vous aide \u00e0 maintenir une temp\u00e9rature id\u00e9ale pendant les vagues de chaleur. Solutions intelligentes pour votre confort et votre bien-\u00eatre en p\u00e9riode de canicule.","breadcrumb":{"@id":"https:\/\/www.astralsecurite.ca\/blogue\/survivre-a-la-canicule-grace-a-la-domotique\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.astralsecurite.ca\/blogue\/survivre-a-la-canicule-grace-a-la-domotique\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.astralsecurite.ca\/blogue\/survivre-a-la-canicule-grace-a-la-domotique\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.astralsecurite.ca\/blogue\/"},{"@type":"ListItem","position":2,"name":"Survivre \u00e0 la canicule gr\u00e2ce \u00e0 la domotique"}]},{"@type":"WebSite","@id":"https:\/\/www.astralsecurite.ca\/blogue\/#website","url":"https:\/\/www.astralsecurite.ca\/blogue\/","name":"Le blogue d'Astral S\u00e9curit\u00e9","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.astralsecurite.ca\/blogue\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.astralsecurite.ca\/blogue\/#\/schema\/person\/07581139837dabeab77172be7d9e7de0","name":"admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.astralsecurite.ca\/blogue\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f09efbcc57bef47e5e43c37ae4f3f265?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f09efbcc57bef47e5e43c37ae4f3f265?s=96&d=mm&r=g","caption":"admin"}}]}},"_links":{"self":[{"href":"https:\/\/www.astralsecurite.ca\/blogue\/wp-json\/wp\/v2\/posts\/1298"}],"collection":[{"href":"https:\/\/www.astralsecurite.ca\/blogue\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.astralsecurite.ca\/blogue\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.astralsecurite.ca\/blogue\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.astralsecurite.ca\/blogue\/wp-json\/wp\/v2\/comments?post=1298"}],"version-history":[{"count":13,"href":"https:\/\/www.astralsecurite.ca\/blogue\/wp-json\/wp\/v2\/posts\/1298\/revisions"}],"predecessor-version":[{"id":1834,"href":"https:\/\/www.astralsecurite.ca\/blogue\/wp-json\/wp\/v2\/posts\/1298\/revisions\/1834"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.astralsecurite.ca\/blogue\/wp-json\/wp\/v2\/media\/1833"}],"wp:attachment":[{"href":"https:\/\/www.astralsecurite.ca\/blogue\/wp-json\/wp\/v2\/media?parent=1298"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.astralsecurite.ca\/blogue\/wp-json\/wp\/v2\/categories?post=1298"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.astralsecurite.ca\/blogue\/wp-json\/wp\/v2\/tags?post=1298"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}